{"id":18906,"date":"2023-11-21T16:05:02","date_gmt":"2023-11-21T15:05:02","guid":{"rendered":"https:\/\/passporterapp.com\/it\/blog\/?p=18906"},"modified":"2023-11-21T16:05:06","modified_gmt":"2023-11-21T15:05:06","slug":"quartiere-gotico-di-barcellona","status":"publish","type":"post","link":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/","title":{"rendered":"Cosa fare e vedere nel Quartiere Gotico di Barcellona"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;18906&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0\\\/5&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Cosa fare e vedere nel Quartiere Gotico di Barcellona&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best}&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n\n<p>Il Quartiere Gotico \u00e8 senza dubbio il cuore della citt\u00e0 e uno dei luoghi imprescindibili di qualsiasi itinerario a Barcellona. \u00c8 la parte pi\u00f9 boh\u00e9mien della citt\u00e0, ricca di bar interessanti e di un&#8217;ampia offerta gastronomica. Delimitato dalle Ramblas, da V\u00eda Laietana, dal Paseo de Col\u00f3n e da Plaza de Catalu\u00f1a, \u00e8 l&#8217;elemento centrale del centro storico di Barcellona. Scoprite attraverso i <strong>bar, i ristoranti e i negozi <\/strong>del Quartiere Gotico l&#8217;essenza vivace e vibrante della citt\u00e0 di Barcellona.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_71 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenuto del post<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a0500dcb27e6\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a0500dcb27e6\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#Quali-sono-i-posti-migliori-da-vedere-nel-Quartiere-Gotico-di-Barcellona\" title=\"Quali sono i posti migliori da vedere nel Quartiere Gotico di Barcellona?\">Quali sono i posti migliori da vedere nel Quartiere Gotico di Barcellona?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#Prima-un-po-di-storia-del-Quartiere-Gotico-di-Barcellona\" title=\"Prima un po&#8217; di storia del Quartiere Gotico di Barcellona\">Prima un po&#8217; di storia del Quartiere Gotico di Barcellona<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#1-Cattedrale-di-Barcellona\" title=\"1. Cattedrale di Barcellona\">1. Cattedrale di Barcellona<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#2-Piazza-del-Re\" title=\"2. Piazza del Re\">2. Piazza del Re<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#3-Museo-della-Storia-di-Barcellona-%E2%80%93-MUHBA\" title=\"3. Museo della Storia di Barcellona &#8211; MUHBA\">3. Museo della Storia di Barcellona &#8211; MUHBA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#4-Plaza-del-Pi\" title=\"4. Plaza del Pi\">4. Plaza del Pi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#5-Basilica-di-Santa-Maria-del-Pi\" title=\"5. Basilica di Santa Maria del Pi\">5. Basilica di Santa Maria del Pi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#6-Piazza-San-Jaime\" title=\"6. Piazza San Jaime\">6. Piazza San Jaime<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#7-Via-Petritxol\" title=\"7. Via Petritxol\">7. Via Petritxol<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#8-Pont-de-Bisbe\" title=\"8. Pont de Bisbe\">8. Pont de Bisbe<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#Dove-mangiare-nel-Quartiere-Gotico\" title=\"Dove mangiare nel Quartiere Gotico?\">Dove mangiare nel Quartiere Gotico?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#Itinerario-di-viaggio-nel-Quartiere-Gotico-di-Barcellona\" title=\"Itinerario di viaggio nel Quartiere Gotico di Barcellona\">Itinerario di viaggio nel Quartiere Gotico di Barcellona<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#Come-organizzare-le-cose-da-vedere-nel-Quartiere-Gotico\" title=\"Come organizzare le cose da vedere nel Quartiere Gotico?\">Come organizzare le cose da vedere nel Quartiere Gotico?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#Domande-frequenti-sulla-visita-al-Quartiere-Gotico-di-Barcellona\" title=\"Domande frequenti sulla visita al Quartiere Gotico di Barcellona\">Domande frequenti sulla visita al Quartiere Gotico di Barcellona<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quali-sono-i-posti-migliori-da-vedere-nel-Quartiere-Gotico-di-Barcellona\"><\/span><strong>Quali sono i posti migliori da vedere nel Quartiere Gotico di Barcellona?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-attachment-id=\"18939\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/attachment\/cosa-vedere-nel-quartiere-gotico-barcellona\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cosa-vedere-nel-quartiere-gotico-barcellona.jpg?fit=683%2C1024&amp;ssl=1\" data-orig-size=\"683,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"cosa-vedere-nel-quartiere-gotico-barcellona\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cosa-vedere-nel-quartiere-gotico-barcellona.jpg?fit=200%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cosa-vedere-nel-quartiere-gotico-barcellona.jpg?fit=683%2C1024&amp;ssl=1\" data-id=\"18939\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cosa-vedere-nel-quartiere-gotico-barcellona.jpg?resize=683%2C1024&#038;ssl=1\" alt=\"cosa vedere nel quartiere gotico barcellona\" class=\"wp-image-18939\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cosa-vedere-nel-quartiere-gotico-barcellona.jpg?w=683&amp;ssl=1 683w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cosa-vedere-nel-quartiere-gotico-barcellona.jpg?resize=200%2C300&amp;ssl=1 200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">@carlotavies<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"678\" height=\"1024\" data-attachment-id=\"18940\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/attachment\/quaartiere-gotico-a-barcellona\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quaartiere-gotico-a-barcellona.jpg?fit=678%2C1024&amp;ssl=1\" data-orig-size=\"678,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"quaartiere-gotico-a-barcellona\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quaartiere-gotico-a-barcellona.jpg?fit=199%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quaartiere-gotico-a-barcellona.jpg?fit=678%2C1024&amp;ssl=1\" data-id=\"18940\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quaartiere-gotico-a-barcellona.jpg?resize=678%2C1024&#038;ssl=1\" alt=\"quartiere gotico a barcellona\" class=\"wp-image-18940\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quaartiere-gotico-a-barcellona.jpg?w=678&amp;ssl=1 678w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quaartiere-gotico-a-barcellona.jpg?resize=199%2C300&amp;ssl=1 199w\" sizes=\"auto, (max-width: 678px) 100vw, 678px\" \/><figcaption class=\"wp-element-caption\">@barta<\/figcaption><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Quartiere Gotico di Barcellona<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Prima-un-po-di-storia-del-Quartiere-Gotico-di-Barcellona\"><\/span><strong>Prima un po&#8217; di storia del Quartiere Gotico di Barcellona<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Il Quartiere Gotico \u00e8 la parte pi\u00f9 antica della citt\u00e0 e del suo centro storico. La struttura del quartiere \u00e8 rimasta quasi intatta fino al XIX secolo, quando le vecchie mura medievali furono demolite e i cimiteri parrocchiali furono trasformati in piazze pubbliche. <\/p>\n\n\n\n<p>Lo storico <strong>Agust\u00edn C\u00f3cola Gant<\/strong> ha svelato questo grande mistero del<strong> Quartiere Gotico di Barcellona<\/strong> nel 2011 con la sua opera <em>El Barrio G\u00f3tico<\/em> <em>de Barcelona de Barcelona<\/em>. Rimarrete sicuramente stupiti dalle strade di questo peculiare quartiere di Barcellona, ricco di ottimi ristoranti, negozi e architetture spettacolari, ma va detto che il suo nome, in quanto tale, \u00e8 una bugia. <\/p>\n\n\n\n<p>Tuttavia, non si pu\u00f2 dire che il Quartiere Gotico sia gotico, piuttosto \u00e8 il risultato dell&#8217;immaginazione del passato medievale catalano durante il XIX secolo, dato che la maggior parte degli edifici non ha pi\u00f9 di 100 anni.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1-Cattedrale-di-Barcellona\"><\/span><strong>1. Cattedrale di Barcellona <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-attachment-id=\"18941\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/attachment\/barrio-gotico-di-barcellona\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/barrio-gotico-di-barcellona.jpg?fit=683%2C1024&amp;ssl=1\" data-orig-size=\"683,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"barrio-gotico-di-barcellona\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/barrio-gotico-di-barcellona.jpg?fit=200%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/barrio-gotico-di-barcellona.jpg?fit=683%2C1024&amp;ssl=1\" data-id=\"18941\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/barrio-gotico-di-barcellona.jpg?resize=683%2C1024&#038;ssl=1\" alt=\"barrio gotico di barcellona\" class=\"wp-image-18941\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/barrio-gotico-di-barcellona.jpg?w=683&amp;ssl=1 683w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/barrio-gotico-di-barcellona.jpg?resize=200%2C300&amp;ssl=1 200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">@amxrrero<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-attachment-id=\"18942\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/attachment\/cosa-vedere-a-barcellona\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cosa-vedere-a-barcellona.jpg?fit=683%2C1024&amp;ssl=1\" data-orig-size=\"683,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"cosa-vedere-a-barcellona\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cosa-vedere-a-barcellona.jpg?fit=200%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cosa-vedere-a-barcellona.jpg?fit=683%2C1024&amp;ssl=1\" data-id=\"18942\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cosa-vedere-a-barcellona.jpg?resize=683%2C1024&#038;ssl=1\" alt=\"cosa vedere a barcellona\" class=\"wp-image-18942\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cosa-vedere-a-barcellona.jpg?w=683&amp;ssl=1 683w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cosa-vedere-a-barcellona.jpg?resize=200%2C300&amp;ssl=1 200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">@merpalmero<\/figcaption><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Cattedrale di Barcellona<\/figcaption><\/figure>\n\n\n\n<p>La Cattedrale \u00e8 senza dubbio una tappa obbligatoria di un <strong>itinerario nel Quartiere Gotico di Barcellona<\/strong>. Dominando la Pla de la Seu, la <strong>Cattedrale di Santa Creu i Santa Eul\u00e0lia<\/strong> presenta un&#8217;imponente facciata gotica che ricorda le grandi cattedrali francesi: \u00e8 lunga 93 metri per 40 metri di larghezza, con un campanile alto 53 metri e una torre principale di 70 metri. <\/p>\n\n\n\n<p>Vale la pena di soffermarsi a osservare il minuzioso intaglio degli <strong>stalli del coro<\/strong>. Di fronte, una scala conduce alla <strong>cripta<\/strong>, che ospita un sarcofago di alabastro con le spoglie di <strong>Sant&#8217;Eulalia<\/strong>, compatrona di Barcellona. Sopra la cripta, l&#8217;<strong>altare<\/strong> poggia su due robusti capitelli visigoti rimasti dalla chiesa originaria. <\/p>\n\n\n\n<p>La domenica mattina, di fronte alla facciata della cattedrale, si svolge un mercato dell&#8217;antiquariato, noto come <strong>mercato gotico<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"769\" height=\"1024\" data-attachment-id=\"18943\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/attachment\/visitare-quartiere-gotico-barcellona\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-quartiere-gotico-barcellona.jpg?fit=769%2C1024&amp;ssl=1\" data-orig-size=\"769,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"visitare-quartiere-gotico-barcellona\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-quartiere-gotico-barcellona.jpg?fit=225%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-quartiere-gotico-barcellona.jpg?fit=769%2C1024&amp;ssl=1\" data-id=\"18943\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-quartiere-gotico-barcellona.jpg?resize=769%2C1024&#038;ssl=1\" alt=\"visitare quartiere gotico barcellona\" class=\"wp-image-18943\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-quartiere-gotico-barcellona.jpg?w=769&amp;ssl=1 769w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-quartiere-gotico-barcellona.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 769px) 100vw, 769px\" \/><figcaption class=\"wp-element-caption\">@thebarcelonadiaries<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"18944\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/attachment\/cattedrale-e-barrio-gotico-barcellona\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cattedrale-e-barrio-gotico-barcellona.jpg?fit=768%2C1024&amp;ssl=1\" data-orig-size=\"768,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"cattedrale-e-barrio-gotico-barcellona\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cattedrale-e-barrio-gotico-barcellona.jpg?fit=225%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cattedrale-e-barrio-gotico-barcellona.jpg?fit=768%2C1024&amp;ssl=1\" data-id=\"18944\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cattedrale-e-barrio-gotico-barcellona.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"cattedrale e barrio gotico barcellona\" class=\"wp-image-18944\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cattedrale-e-barrio-gotico-barcellona.jpg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/cattedrale-e-barrio-gotico-barcellona.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">@nattsevillano<\/figcaption><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Quartiere gotico<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2-Piazza-del-Re\"><\/span><strong>2. Piazza del Re<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Fin dall&#8217;Alto Medioevo, la <strong>Piazza del Re<\/strong> ospitava il Palazzo Reale, una delle principali residenze dei conti di Barcellona, che dovreste vedere durante la vostra passeggiata nel Quartiere Gotico di Barcellona. La struttura originaria, costruita sopra le <strong>mura romane<\/strong>, era simile a quella di una fortezza, ma nel corso dei secoli sono stati aggiunti altri edifici. Quasi tutto ci\u00f2 che possiamo vedere oggi risale ai secoli XIV e XV e, insieme ai resti archeologici del sottosuolo, costituisce il <strong>Museo Storico della Citt\u00e0<\/strong>, la cui visita vi condurr\u00e0 in un viaggio attraverso i primi 1500 anni di vita di Barcellona.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p><em>Organizzate il vostro itinerario di viaggio con <a href=\"https:\/\/passporterapp.com\/it\/auth\/signup?ref=blogpassporter&amp;utm_source=blog&amp;utm_medium=que-ver-en-rabat&amp;utm_term=registro-gratis\" target=\"_blank\" rel=\"noreferrer noopener\">Passporter<\/a>, totalmente gratuito, facile e funzionale. Lasciatevi ispirare dalle esperienze degli altri viaggiatori e scegliete i luoghi che pi\u00f9 vi interessano aggiungendoli alla mappa dell&#8217;itinerario.<\/em><\/p><\/blockquote><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3-Museo-della-Storia-di-Barcellona-%E2%80%93-MUHBA\"><\/span><strong>3. Museo della Storia di Barcellona &#8211; MUHBA<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Il Museo della Storia di Barcellona (MUHBA) conserva, studia, documenta, diffonde ed espone il patrimonio storico e la storia di Barcellona dalle origini ai giorni nostri. Riunisce vari centri patrimoniali rilevanti per la storia della citt\u00e0, distribuiti nei suoi quartieri e distretti, e la sua sede si trova nella Casa Padell\u00e0s, uno degli edifici che compongono il complesso monumentale di Plazza del Re, nel Quartiere Gotico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"pla\u00e7a-del-pi\"><span class=\"ez-toc-section\" id=\"4-Plaza-del-Pi\"><\/span>4. Plaza del Pi<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>La confluenza di Plaza del Pi, situata vicino alle Ramblas, \u00e8 uno dei luoghi pi\u00f9 noti di Barcellona per artisti e boh\u00e9mien. L&#8217;area \u00e8 dominata dalla Chiesa di Santa Maria del Pi con il suo grande rosone colorato. Nella piazza si tengono spesso fiere d&#8217;arte e di artigianato, nonch\u00e9 vendite di alimenti naturali come il miele e il &#8220;mat\u00f3&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-attachment-id=\"18945\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/attachment\/visitare-barcellona\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-barcellona.jpg?fit=819%2C1024&amp;ssl=1\" data-orig-size=\"819,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"visitare-barcellona\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-barcellona.jpg?fit=240%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-barcellona.jpg?fit=819%2C1024&amp;ssl=1\" data-id=\"18945\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-barcellona.jpg?resize=819%2C1024&#038;ssl=1\" alt=\"visitare barcellona\" class=\"wp-image-18945\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-barcellona.jpg?w=819&amp;ssl=1 819w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-barcellona.jpg?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/visitare-barcellona.jpg?resize=768%2C960&amp;ssl=1 768w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">@esterg<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-attachment-id=\"18946\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/attachment\/vacanza-barrio-gotico-barcellona\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/vacanza-barrio-gotico-barcellona.jpg?fit=768%2C1024&amp;ssl=1\" data-orig-size=\"768,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"vacanza-barrio-gotico-barcellona\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/vacanza-barrio-gotico-barcellona.jpg?fit=225%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/vacanza-barrio-gotico-barcellona.jpg?fit=768%2C1024&amp;ssl=1\" data-id=\"18946\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/vacanza-barrio-gotico-barcellona.jpg?resize=768%2C1024&#038;ssl=1\" alt=\"vacanza barrio gotico barcellona\" class=\"wp-image-18946\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/vacanza-barrio-gotico-barcellona.jpg?w=768&amp;ssl=1 768w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/vacanza-barrio-gotico-barcellona.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">@ainoafraga3<\/figcaption><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Il quartiere gotico di Barcellona<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5-Basilica-di-Santa-Maria-del-Pi\"><\/span><strong>5. Basilica di Santa Maria del Pi<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Costruita nel XIV secolo, \u00e8 uno degli esempi pi\u00f9 rappresentativi dell&#8217;architettura religiosa gotica catalana. L&#8217;edificio fu costruito tra il 1306 e il 1391. Tra le opere d&#8217;arte che ospita vi sono l&#8217;altare di Sant Miquel e le vetrate, opera di Antoni Viladomat (XVIII secolo). <\/p>\n\n\n\n<p>La chiesa di Santa Maria del Pi a Barcellona fu costruita nel <strong>XIV secolo<\/strong> ed \u00e8 uno degli esempi pi\u00f9 rappresentativi dell&#8217;architettura <strong>religiosa gotica catalana<\/strong>. Questo stile \u00e8 caratterizzato da una marcata orizzontalit\u00e0 e da una perfetta disposizione delle masse che strutturano le <strong>pareti quasi cieche e prive di decorazioni scultoree.<\/strong> Senza dubbio vi consigliamo di visitare l&#8217;interno della chiesa gotica di Santa Maria del Pi, coronata da uno spettacolare rosone di 10 metri di diametro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"6-Piazza-San-Jaime\"><\/span><strong>6. Piazza San Jaime <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Oggi \u00e8 la sede del Comune di Barcellona e del governo della Generalitat de Catalunya. Era il F\u00f2rum o centro pubblico e politico in epoca romana e, naturalmente, in epoca medievale. <\/p>\n\n\n\n<p>Il Palau de la Generalitat \u00e8 stato costruito in stile gotico, anche se la facciata principale che si affaccia sulla piazza risale al periodo rinascimentale ed \u00e8 stata progettata dal capomastro catalano Pere Blai. <\/p>\n\n\n\n<p>La facciata gotica \u00e8 stata conservata, nel gi\u00e0 citato Carrer del Bisbe. Proprio di fronte, si trova la facciata neoclassica dell&#8217;Ajuntament (Municipio), opera del XIX secolo di Josep Mas i Vila. Naturalmente, conserva anche l&#8217;originale facciata gotica, situata su uno dei suoi lati.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.passporterapp.android&amp;gl=IT\" style=\"background-color:#2a7057\" target=\"_blank\" rel=\"noreferrer noopener\">Scaricate l&#8217;app passpporter, \u00e8 gratis! \ud83d\ude42<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"7-Via-Petritxol\"><\/span><strong>7. Via Petritxol<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Passeggiando per il Quartiere Gotico si pu\u00f2 trovare di tutto, ma oggi mi sono fermata in una delle vie pi\u00f9 amate dai golosi di Barcellona. Si tratta della <strong>carismatica Via Petritxol<\/strong>, conosciuta da molti anche come la <em>via del cioccolato<\/em>.<\/p>\n\n\n\n<p>Quindi, per gli amanti del cioccolato e per chiunque venga a Barcellona e passeggi per il centro in una giornata invernale, una cosa essenziale da fare \u00e8: bere una cioccolata calda! La via Petritxol \u00e8 la pi\u00f9 conosciuta per la tradizionale cioccolata e anche il luogo pi\u00f9 storico per gustarla.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"8-Pont-de-Bisbe\"><\/span><strong>8. Pont de Bisbe<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Il <strong><em>Pont del Bisbe <\/em><\/strong>\u00e8 forse una delle <strong>immagini pi\u00f9 riconoscibili di Barcellona<\/strong>, e sicuramente del Quartiere Gotico. \u00c8 un ponte sopraelevato che collega il palazzo della <em>Generalitat de Catalunya<\/em> con la Casa dels Canons. Costruito nel 1928 da Joan Rubi\u00f3, un discepolo di Gaud\u00ed.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Dove-mangiare-nel-Quartiere-Gotico\"><\/span><strong>Dove mangiare nel Quartiere Gotico?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"678\" height=\"1024\" data-attachment-id=\"18947\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/attachment\/dove-mangiare-quartiere-goticobarcellona\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/dove-mangiare-quartiere-goticobarcellona.jpg?fit=678%2C1024&amp;ssl=1\" data-orig-size=\"678,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dove-mangiare-quartiere-goticobarcellona\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/dove-mangiare-quartiere-goticobarcellona.jpg?fit=199%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/dove-mangiare-quartiere-goticobarcellona.jpg?fit=678%2C1024&amp;ssl=1\" data-id=\"18947\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/dove-mangiare-quartiere-goticobarcellona.jpg?resize=678%2C1024&#038;ssl=1\" alt=\"dove mangiare quartiere gotico barcellona\" class=\"wp-image-18947\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/dove-mangiare-quartiere-goticobarcellona.jpg?w=678&amp;ssl=1 678w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/dove-mangiare-quartiere-goticobarcellona.jpg?resize=199%2C300&amp;ssl=1 199w\" sizes=\"auto, (max-width: 678px) 100vw, 678px\" \/><figcaption class=\"wp-element-caption\">@barta<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-attachment-id=\"18948\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/attachment\/ristoranti-quartiere-gotico-barcellona\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/ristoranti-quartiere-gotico-barcellona.jpg?fit=683%2C1024&amp;ssl=1\" data-orig-size=\"683,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"ristoranti-quartiere-gotico-barcellona\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/ristoranti-quartiere-gotico-barcellona.jpg?fit=200%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/ristoranti-quartiere-gotico-barcellona.jpg?fit=683%2C1024&amp;ssl=1\" data-id=\"18948\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/ristoranti-quartiere-gotico-barcellona.jpg?resize=683%2C1024&#038;ssl=1\" alt=\"ristoranti quartiere gotico barcellona\" class=\"wp-image-18948\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/ristoranti-quartiere-gotico-barcellona.jpg?w=683&amp;ssl=1 683w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/ristoranti-quartiere-gotico-barcellona.jpg?resize=200%2C300&amp;ssl=1 200w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">@sebas_pozzi<\/figcaption><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Ristoranti nel Quartiere Gotico<\/figcaption><\/figure>\n\n\n\n<p>Il Quartiere Gotico offre una vasta gamma di offerte gastronomiche e alcuni dei ristoranti pi\u00f9 rinomati della citt\u00e0. Ecco una piccola selezione dei migliori ristoranti del quartiere dove mangiare e cenare a Barcellona, per eccellenza.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La Lubina<\/li>\n\n\n\n<li>Viana<\/li>\n\n\n\n<li>Brugarol Barcelona<\/li>\n\n\n\n<li>Paz 19 by Sensi Tapas Bar<\/li>\n\n\n\n<li>Pizzeria Da Nanni Barcelona.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Itinerario-di-viaggio-nel-Quartiere-Gotico-di-Barcellona\"><\/span><strong>Itinerario di viaggio nel Quartiere Gotico di Barcellona<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Qui vi lasciamo la nostra mappa con i luoghi che vi consigliamo di visitare nel Quartiere Gotico di Barcellona, in modo che possiate organizzare il vostro viaggio in modo semplice e veloce. Potete anche aggiungere documenti importanti come biglietti di viaggio, prenotazioni alberghiere e persino invitare i vostri amici a partecipare all&#8217;organizzazione dell&#8217;itinerario. <strong>L&#8217;utilizzo di Passporter \u00e8 gratuito e vi aiuter\u00e0 a viaggiare in modo pi\u00f9 organizzato<\/strong>. \u00c8 possibile <a href=\"https:\/\/passporterapp.com\/it\/auth\/signup?ref=blogpassporter&amp;utm_source=blog&amp;utm_medium=que-ver-en-rabat&amp;utm_term=registro-gratis\" target=\"_blank\" rel=\"noreferrer noopener\">registrarsi sul sito web<\/a> o <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.passporterapp.android&amp;gl=IT\" target=\"_blank\" rel=\"noreferrer noopener\">scaricare l&#8217;app<\/a> per avere tutto centralizzato e in tasca?<\/p>\n\n\n\n<p><iframe loading=\"lazy\" width=\"100%\" height=\"400\" style=\"border: 0\" src=\"https:\/\/passporterapp.com\/frame\/itineraries\/70a90d6a-432a-440b-8643-8cf9a44105a4?ref=blogpassporter&amp;utm_source=blog&amp;utm_medium=que-ver-barrio-gotico&amp;utm_term=mapita\"><\/p>\n<p><\/iframe><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-come-organizzare-le-cose-da-vedere-nel-quartiere-gotico\"><span class=\"ez-toc-section\" id=\"Come-organizzare-le-cose-da-vedere-nel-Quartiere-Gotico\"><\/span><strong>Come organizzare le cose da vedere nel Quartiere Gotico?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lasciatevi ispirare dalle esperienze degli altri viaggiatori, dalle loro foto e dai loro itinerari.<\/li>\n\n\n\n<li>Organizzate il vostro viaggio in base alle categorie che preferite: date, numero di giorni o tipo di viaggio (spiaggia, montagna, ristoranti\u2026).<\/li>\n\n\n\n<li><strong>Aggiungete i vostri amici<\/strong> in modo che possano vedere e modificare tutti i vostri piani e le informazioni di viaggio.<\/li>\n\n\n\n<li>Create il vostro itinerario della destinazione con tutto ci\u00f2 che volete visitare ogni giorno.<\/li>\n\n\n\n<li>Aggiungete le tappe che vi interessano di pi\u00f9, compresi gli alloggi, i ristoranti, i musei\u2026<\/li>\n\n\n\n<li>Prenotate voli, alloggi, trasferimenti e attivit\u00e0<strong> attraverso un&#8217;unica app.<\/strong><\/li>\n\n\n\n<li><strong>Salvate tutti i documenti nell&#8217;app<\/strong> per avere sempre tutto a portata di mano: prenotazioni, carte d&#8217;imbarco, documenti importanti\u2026<\/li>\n\n\n\n<li>Apportate le modifiche necessarie e tutto sar\u00e0 pronto per il vostro viaggio.<\/li>\n\n\n\n<li><strong>Condividete la vostra esperienza con altri utenti<\/strong>. Caricate sull&#8217;app le foto dei luoghi che avete visitato durante il vostro viaggio e ispirate altri viaggiatori con la vostra esperienza. <\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p><em>Se avete dubbi su come utilizzare l&#8217;app Passporter, potete consultare il nostro post: <strong><a href=\"https:\/\/passporterapp.com\/it\/blog\/viaggio\/itinerario-di-viaggio\/\" target=\"_blank\" rel=\"noreferrer noopener\">Come creare un itinerario di viaggio in Passporter<\/a><\/strong>.<\/em><\/p><\/blockquote><\/figure>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/passporterapp.com\/it\/auth\/signup?ref=blogpassporter&amp;utm_source=blog&amp;utm_medium=que-ver-en-rabat&amp;utm_term=registro-gratis\" style=\"background-color:#2a7057\" target=\"_blank\" rel=\"noreferrer noopener\">Registratevi gratis e create il vostro itinerario di viaggio<\/a><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Domande-frequenti-sulla-visita-al-Quartiere-Gotico-di-Barcellona\"><\/span><strong>Domande frequenti sulla visita al Quartiere Gotico di Barcellona<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1627056182383\"><strong class=\"schema-faq-question\">Come muoversi nel Quartiere Gotico?<\/strong> <p class=\"schema-faq-answer\">Il Quartiere Gotico \u00e8 un quartiere da conoscere a piedi, per poter percorrere tutte le sue stradine e scoprire gli angoli pi\u00f9 interessanti che ha da offrire.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1627056593394\"><strong class=\"schema-faq-question\">Dove dormire nel Quartiere Gotico di Barcellona?<\/strong> <p class=\"schema-faq-answer\">Il Quartiere Gotico \u00e8 il cuore storico di Barcellona e il luogo ideale per visitare molte delle attrazioni della citt\u00e0. \u00c8 senza dubbio uno dei quartieri migliori in cui soggiornare, quindi vi lasciamo con questa piccola selezione di alloggi nel Quartiere Gotico.<br\/>&#8211;\u00a0The Wittmore Barcelona<br\/>&#8211;\u00a0Catalonia Magdalenes Hotel\u00a0<br\/><\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1627056648632\"><strong class=\"schema-faq-question\">Quanto costa il biglietto d&#8217;ingresso al Museo Storico di Barcellona?<\/strong> <p class=\"schema-faq-answer\"><strong>Ingresso normale<\/strong>: 7 \u20ac.<br\/><strong>Gruppi superiori a 10 persone<\/strong>: 5 \u20ac.<br\/><strong>Ingresso ridotto<\/strong>: 5 \u20ac, studenti sotto i 29 anni, anziani sopra i 65 anni.<br\/><strong>Ingresso gratuito<\/strong>: bambini sotto i 16 anni, carta rosa gratuita, membri dell&#8217;ICOM, della Barcellona Card e delle Associazioni di Museologi della Catalogna o guide turistiche.<br\/><\/p> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il Quartiere Gotico \u00e8 senza dubbio il cuore della citt\u00e0 e uno dei luoghi imprescindibili di qualsiasi itinerario a Barcellona. \u00c8 la parte pi\u00f9 boh\u00e9mien della citt\u00e0, ricca di bar interessanti e di un&#8217;ampia offerta gastronomica. Delimitato dalle Ramblas, da V\u00eda Laietana, dal Paseo de Col\u00f3n e da Plaza de Catalu\u00f1a, \u00e8 l&#8217;elemento centrale del centro storico di Barcellona. Scoprite attraverso i bar, i ristoranti e i negozi del Quartiere Gotico l&#8217;essenza vivace e vibrante della citt\u00e0 di Barcellona. Quali sono i posti migliori da vedere nel Quartiere Gotico di Barcellona? Prima un po&#8217; di storia del Quartiere Gotico di Barcellona Il Quartiere Gotico \u00e8 la parte pi\u00f9 antica della citt\u00e0 e del suo centro storico. La struttura del quartiere \u00e8 rimasta quasi intatta fino al XIX secolo, quando le vecchie mura medievali furono demolite [&hellip;]<\/p>\n","protected":false},"author":183705631,"featured_media":18907,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1467],"tags":[],"class_list":["post-18906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spagna"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.0 (Yoast SEO v24.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cosa fare e vedere nel Quartiere Gotico di Barcellona - Passporter Blog<\/title>\n<meta name=\"description\" content=\"Scoprite attraverso i bar, i ristoranti e i negozi del Barrio Gotico, l&#039;essenza vivace e vibrante della citt\u00e0 di Barcellona.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cosa fare e vedere nel Quartiere Gotico di Barcellona\" \/>\n<meta property=\"og:description\" content=\"Scoprite attraverso i bar, i ristoranti e i negozi del Barrio Gotico, l&#039;essenza vivace e vibrante della citt\u00e0 di Barcellona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/\" \/>\n<meta property=\"og:site_name\" content=\"Passporter Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-21T15:05:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-21T15:05:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quartiere-gotico-di-Barcellona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Liliana Giardini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Liliana Giardini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/\",\"url\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/\",\"name\":\"Cosa fare e vedere nel Quartiere Gotico di Barcellona - Passporter Blog\",\"isPartOf\":{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quartiere-gotico-di-Barcellona.jpg?fit=1024%2C678&ssl=1\",\"datePublished\":\"2023-11-21T15:05:02+00:00\",\"dateModified\":\"2023-11-21T15:05:06+00:00\",\"author\":{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/#\/schema\/person\/22fd16d483bf13298d880cc3b645e5b9\"},\"description\":\"Scoprite attraverso i bar, i ristoranti e i negozi del Barrio Gotico, l'essenza vivace e vibrante della citt\u00e0 di Barcellona.\",\"breadcrumb\":{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056182383\"},{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056593394\"},{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056648632\"}],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quartiere-gotico-di-Barcellona.jpg?fit=1024%2C678&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quartiere-gotico-di-Barcellona.jpg?fit=1024%2C678&ssl=1\",\"width\":1024,\"height\":678,\"caption\":\"quartiere gotico di Barcellona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/passporterapp.com\/it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosa fare e vedere nel Quartiere Gotico di Barcellona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/#website\",\"url\":\"https:\/\/passporterapp.com\/it\/blog\/\",\"name\":\"Passporter Blog\",\"description\":\"Passporter Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/passporterapp.com\/it\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/#\/schema\/person\/22fd16d483bf13298d880cc3b645e5b9\",\"name\":\"Liliana Giardini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2eddda6668145eaaa587a8f6407fcc8326201192dbd3195f3a45b095acbaaf9b?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2eddda6668145eaaa587a8f6407fcc8326201192dbd3195f3a45b095acbaaf9b?s=96&d=identicon&r=g\",\"caption\":\"Liliana Giardini\"},\"url\":\"https:\/\/passporterapp.com\/it\/blog\/author\/liliana-giardini\/\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056182383\",\"position\":1,\"url\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056182383\",\"name\":\"Come muoversi nel Quartiere Gotico?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Il Quartiere Gotico \u00e8 un quartiere da conoscere a piedi, per poter percorrere tutte le sue stradine e scoprire gli angoli pi\u00f9 interessanti che ha da offrire.\",\"inLanguage\":\"it-IT\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056593394\",\"position\":2,\"url\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056593394\",\"name\":\"Dove dormire nel Quartiere Gotico di Barcellona?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Il Quartiere Gotico \u00e8 il cuore storico di Barcellona e il luogo ideale per visitare molte delle attrazioni della citt\u00e0. \u00c8 senza dubbio uno dei quartieri migliori in cui soggiornare, quindi vi lasciamo con questa piccola selezione di alloggi nel Quartiere Gotico.<br\/>-\u00a0The Wittmore Barcelona<br\/>-\u00a0Catalonia Magdalenes Hotel\u00a0<br\/>\",\"inLanguage\":\"it-IT\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056648632\",\"position\":3,\"url\":\"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056648632\",\"name\":\"Quanto costa il biglietto d'ingresso al Museo Storico di Barcellona?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<strong>Ingresso normale<\/strong>: 7 \u20ac.<br\/><strong>Gruppi superiori a 10 persone<\/strong>: 5 \u20ac.<br\/><strong>Ingresso ridotto<\/strong>: 5 \u20ac, studenti sotto i 29 anni, anziani sopra i 65 anni.<br\/><strong>Ingresso gratuito<\/strong>: bambini sotto i 16 anni, carta rosa gratuita, membri dell'ICOM, della Barcellona Card e delle Associazioni di Museologi della Catalogna o guide turistiche.<br\/>\",\"inLanguage\":\"it-IT\"},\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cosa fare e vedere nel Quartiere Gotico di Barcellona - Passporter Blog","description":"Scoprite attraverso i bar, i ristoranti e i negozi del Barrio Gotico, l'essenza vivace e vibrante della citt\u00e0 di Barcellona.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/","og_locale":"it_IT","og_type":"article","og_title":"Cosa fare e vedere nel Quartiere Gotico di Barcellona","og_description":"Scoprite attraverso i bar, i ristoranti e i negozi del Barrio Gotico, l'essenza vivace e vibrante della citt\u00e0 di Barcellona.","og_url":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/","og_site_name":"Passporter Blog","article_published_time":"2023-11-21T15:05:02+00:00","article_modified_time":"2023-11-21T15:05:06+00:00","og_image":[{"width":1024,"height":678,"url":"https:\/\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quartiere-gotico-di-Barcellona.jpg","type":"image\/jpeg"}],"author":"Liliana Giardini","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Liliana Giardini","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","FAQPage"],"@id":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/","url":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/","name":"Cosa fare e vedere nel Quartiere Gotico di Barcellona - Passporter Blog","isPartOf":{"@id":"https:\/\/passporterapp.com\/it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#primaryimage"},"image":{"@id":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quartiere-gotico-di-Barcellona.jpg?fit=1024%2C678&ssl=1","datePublished":"2023-11-21T15:05:02+00:00","dateModified":"2023-11-21T15:05:06+00:00","author":{"@id":"https:\/\/passporterapp.com\/it\/blog\/#\/schema\/person\/22fd16d483bf13298d880cc3b645e5b9"},"description":"Scoprite attraverso i bar, i ristoranti e i negozi del Barrio Gotico, l'essenza vivace e vibrante della citt\u00e0 di Barcellona.","breadcrumb":{"@id":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056182383"},{"@id":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056593394"},{"@id":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056648632"}],"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#primaryimage","url":"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quartiere-gotico-di-Barcellona.jpg?fit=1024%2C678&ssl=1","contentUrl":"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quartiere-gotico-di-Barcellona.jpg?fit=1024%2C678&ssl=1","width":1024,"height":678,"caption":"quartiere gotico di Barcellona"},{"@type":"BreadcrumbList","@id":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/passporterapp.com\/it\/blog\/"},{"@type":"ListItem","position":2,"name":"Cosa fare e vedere nel Quartiere Gotico di Barcellona"}]},{"@type":"WebSite","@id":"https:\/\/passporterapp.com\/it\/blog\/#website","url":"https:\/\/passporterapp.com\/it\/blog\/","name":"Passporter Blog","description":"Passporter Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/passporterapp.com\/it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/passporterapp.com\/it\/blog\/#\/schema\/person\/22fd16d483bf13298d880cc3b645e5b9","name":"Liliana Giardini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/passporterapp.com\/it\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2eddda6668145eaaa587a8f6407fcc8326201192dbd3195f3a45b095acbaaf9b?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2eddda6668145eaaa587a8f6407fcc8326201192dbd3195f3a45b095acbaaf9b?s=96&d=identicon&r=g","caption":"Liliana Giardini"},"url":"https:\/\/passporterapp.com\/it\/blog\/author\/liliana-giardini\/"},{"@type":"Question","@id":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056182383","position":1,"url":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056182383","name":"Come muoversi nel Quartiere Gotico?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Il Quartiere Gotico \u00e8 un quartiere da conoscere a piedi, per poter percorrere tutte le sue stradine e scoprire gli angoli pi\u00f9 interessanti che ha da offrire.","inLanguage":"it-IT"},"inLanguage":"it-IT"},{"@type":"Question","@id":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056593394","position":2,"url":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056593394","name":"Dove dormire nel Quartiere Gotico di Barcellona?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Il Quartiere Gotico \u00e8 il cuore storico di Barcellona e il luogo ideale per visitare molte delle attrazioni della citt\u00e0. \u00c8 senza dubbio uno dei quartieri migliori in cui soggiornare, quindi vi lasciamo con questa piccola selezione di alloggi nel Quartiere Gotico.<br\/>-\u00a0The Wittmore Barcelona<br\/>-\u00a0Catalonia Magdalenes Hotel\u00a0<br\/>","inLanguage":"it-IT"},"inLanguage":"it-IT"},{"@type":"Question","@id":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056648632","position":3,"url":"https:\/\/passporterapp.com\/it\/blog\/spagna\/quartiere-gotico-di-barcellona\/#faq-question-1627056648632","name":"Quanto costa il biglietto d'ingresso al Museo Storico di Barcellona?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"<strong>Ingresso normale<\/strong>: 7 \u20ac.<br\/><strong>Gruppi superiori a 10 persone<\/strong>: 5 \u20ac.<br\/><strong>Ingresso ridotto<\/strong>: 5 \u20ac, studenti sotto i 29 anni, anziani sopra i 65 anni.<br\/><strong>Ingresso gratuito<\/strong>: bambini sotto i 16 anni, carta rosa gratuita, membri dell'ICOM, della Barcellona Card e delle Associazioni di Museologi della Catalogna o guide turistiche.<br\/>","inLanguage":"it-IT"},"inLanguage":"it-IT"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/11\/quartiere-gotico-di-Barcellona.jpg?fit=1024%2C678&ssl=1","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pd1Cww-4UW","_links":{"self":[{"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/posts\/18906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/users\/183705631"}],"replies":[{"embeddable":true,"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/comments?post=18906"}],"version-history":[{"count":0,"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/posts\/18906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/media\/18907"}],"wp:attachment":[{"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/media?parent=18906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/categories?post=18906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/tags?post=18906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}