{"id":14041,"date":"2023-12-29T11:00:00","date_gmt":"2023-12-29T10:00:00","guid":{"rendered":"https:\/\/passporterapp.com\/it\/blog\/?p=14041"},"modified":"2023-12-29T13:07:38","modified_gmt":"2023-12-29T12:07:38","slug":"valle-cocora-colombia","status":"publish","type":"post","link":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/","title":{"rendered":"Valle di Cocora in Colombia"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;14041&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5\\\/5&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Valle di Cocora in Colombia&quot;,&quot;width&quot;:&quot;138&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best}&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 138px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5    <\/div>\n    <\/div>\n\n<p>La Valle di Cocora \u00e8 un meraviglioso paesaggio naturale situato nel cuore dell&#8217;Eje Cafetero della Colombia. L\u00ec si possono osservare le palme pi\u00f9 alte del mondo che si perdono nella nebbia al tramonto, creando una vista tanto bella quanto magica e spettrale. Ti invitiamo a scoprire le attivit\u00e0 e le bellezze di questa valle che conquistano ogni avventuriero che ci mette piede.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_71 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenuto del post<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04e43d78487\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04e43d78487\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#Cose-la-Valle-di-Cocora\" title=\"Cos&#8217;\u00e8 la Valle di Cocora?\">Cos&#8217;\u00e8 la Valle di Cocora?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#Cosa-vedere-nella-Valle-di-Cocora\" title=\"Cosa vedere nella Valle di Cocora?\">Cosa vedere nella Valle di Cocora?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#1-Il-Bosque-de-las-Palmas\" title=\"1. Il Bosque de las Palmas\">1. Il Bosque de las Palmas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#2-Acaime-la-riserva-dei-colibri\" title=\"2. Acaime: la riserva dei colibr\u00ec\">2. Acaime: la riserva dei colibr\u00ec<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#3-Punti-panoramici\" title=\"3. Punti panoramici\">3. Punti panoramici<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#4-Mano-di-Acaime\" title=\"4. Mano di Acaime\">4. Mano di Acaime<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#Cosa-fare-nella-Valle-di-Cocora\" title=\"Cosa fare nella Valle di Cocora\">Cosa fare nella Valle di Cocora<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#1-Trekking-nella-Valle-di-Cocora\" title=\"1. Trekking nella Valle di Cocora\">1. Trekking nella Valle di Cocora<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#2-Giro-a-cavallo\" title=\"2. Giro a cavallo\">2. Giro a cavallo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#3-Picnic\" title=\"3. Picnic\">3. Picnic<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#4-Yoga\" title=\"4. Yoga\">4. Yoga<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#5-Piantare-una-palma\" title=\"5. Piantare una palma\">5. Piantare una palma<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#6-Visita-Salento\" title=\"6. Visita Salento\">6. Visita Salento<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#Mappa-di-viaggio-Valle-di-Cocora\" title=\"Mappa di viaggio Valle di Cocora\">Mappa di viaggio Valle di Cocora<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#Come-raggiungere-la-Valle-del-Cocora\" title=\"Come raggiungere la Valle del Cocora?\">Come raggiungere la Valle del Cocora?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#Dove-alloggiare-nella-Valle-di-Cocora\" title=\"Dove alloggiare nella Valle di Cocora?\">Dove alloggiare nella Valle di Cocora?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#Consigli-per-il-vostro-viaggio-nella-Valle-del-Cocora\" title=\"Consigli per il vostro viaggio nella Valle del Cocora\">Consigli per il vostro viaggio nella Valle del Cocora<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#Come-organizzare-il-vostro-viaggio-nella-Valle-del-Cocora\" title=\"Come organizzare il vostro viaggio nella Valle del Cocora?\">Come organizzare il vostro viaggio nella Valle del Cocora?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#Domande-frequenti-su-un-viaggio-nella-Valle-di-Cocora\" title=\"Domande frequenti su un viaggio nella Valle di Cocora\">Domande frequenti su un viaggio nella Valle di Cocora<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-cos-e-la-valle-di-cocora\"><span class=\"ez-toc-section\" id=\"Cose-la-Valle-di-Cocora\"><\/span><strong>Cos&#8217;\u00e8 la Valle di Cocora?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La Valle di Cocora \u00e8 un meraviglioso paesaggio naturale situato nella catena montuosa centrale delle Ande colombiane, tra gli alti corsi del fiume Quindio. Pi\u00f9 precisamente, nella citt\u00e0 di Salento, a 30 km da Armenia, nel dipartimento di Quind\u00edo, uno dei punti chiave dell&#8217;Eje Cafetero.<\/p>\n\n\n\n<p>Questa valle \u00e8 anche una delle entrate del Parque Nacional Natural de los Nevados, un enorme parco protetto di 583 km\u00b2 caratterizzato da laghi, foreste e vulcani, alcuni dei quali attivi, con cime innevate.<\/p>\n\n\n\n<p>La Valle di Cocora vanta una grande diversit\u00e0 di flora e fauna. Infatti, una delle principali attrazioni di questo parco sono le sue enormi <strong>Quind\u00edo Wax Palms, le pi\u00f9 alte del mondo e l&#8217;albero nazionale della Colombia<\/strong>. Per quanto riguarda la sua fauna, si pu\u00f2 trovare una grande moltitudine di specie, dai puma ai colibr\u00ec e persino le mucche che vagano liberamente in alcune zone.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"729\" height=\"1024\" data-attachment-id=\"19204\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/valle-del-cocora-en-salento-729x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-en-Salento-729x1024-1.jpg?fit=729%2C1024&amp;ssl=1\" data-orig-size=\"729,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Valle-del-cocora-en-Salento-729&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-en-Salento-729x1024-1.jpg?fit=214%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-en-Salento-729x1024-1.jpg?fit=729%2C1024&amp;ssl=1\" data-id=\"19204\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-en-Salento-729x1024-1.jpg?resize=729%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19204\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-en-Salento-729x1024-1.jpg?w=729&amp;ssl=1 729w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-en-Salento-729x1024-1.jpg?resize=214%2C300&amp;ssl=1 214w\" sizes=\"auto, (max-width: 729px) 100vw, 729px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"613\" height=\"1024\" data-attachment-id=\"19205\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/que-hacer-en-el-valle-del-cocora-613x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/que-hacer-en-el-valle-del-Cocora-613x1024-1.jpg?fit=613%2C1024&amp;ssl=1\" data-orig-size=\"613,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"que-hacer-en-el-valle-del-Cocora-613&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/que-hacer-en-el-valle-del-Cocora-613x1024-1.jpg?fit=180%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/que-hacer-en-el-valle-del-Cocora-613x1024-1.jpg?fit=613%2C1024&amp;ssl=1\" data-id=\"19205\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/que-hacer-en-el-valle-del-Cocora-613x1024-1.jpg?resize=613%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19205\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/que-hacer-en-el-valle-del-Cocora-613x1024-1.jpg?w=613&amp;ssl=1 613w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/que-hacer-en-el-valle-del-Cocora-613x1024-1.jpg?resize=180%2C300&amp;ssl=1 180w\" sizes=\"auto, (max-width: 613px) 100vw, 613px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"717\" height=\"1024\" data-attachment-id=\"19206\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/valle-del-cocora-colombia-717x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Colombia-717x1024-1.jpg?fit=717%2C1024&amp;ssl=1\" data-orig-size=\"717,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Valle-del-Cocora-Colombia-717&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Colombia-717x1024-1.jpg?fit=210%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Colombia-717x1024-1.jpg?fit=717%2C1024&amp;ssl=1\" data-id=\"19206\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Colombia-717x1024-1.jpg?resize=717%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19206\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Colombia-717x1024-1.jpg?w=717&amp;ssl=1 717w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Colombia-717x1024-1.jpg?resize=210%2C300&amp;ssl=1 210w\" sizes=\"auto, (max-width: 717px) 100vw, 717px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Viaggio nella Valle del Cocora in Colombia @voyagefox_<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cosa-vedere-nella-Valle-di-Cocora\"><\/span><strong>Cosa vedere nella Valle di Cocora?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La Valle della Cocora pu\u00f2 essere percorsa in un itinerario di 6 ore con diverse e impressionanti fermate. Qui ti raccontiamo le cose da non perdere:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1-Il-Bosque-de-las-Palmas\"><\/span><strong>1. Il Bosque de las Palmas<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Questa zona della valle \u00e8 senza dubbio la pi\u00f9 rappresentativa. Il Bosque de las Palmas ospita l&#8217;85% delle palme da cera della Colombia. Questi alberi, oltre ad essere uno dei simboli nazionali, sono le palme pi\u00f9 alte del mondo, con esemplari alti pi\u00f9 di 60 metri. Purtroppo, la palma di cera \u00e8 una specie in pericolo, il che rende questa visita ancora pi\u00f9 speciale.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"752\" height=\"1024\" data-attachment-id=\"19207\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/las-palmas-del-valle-del-cocora-752x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Las-palmas-del-Valle-del-Cocora-752x1024-1.jpg?fit=752%2C1024&amp;ssl=1\" data-orig-size=\"752,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Las-palmas-del-Valle-del-Cocora-752&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Las-palmas-del-Valle-del-Cocora-752x1024-1.jpg?fit=220%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Las-palmas-del-Valle-del-Cocora-752x1024-1.jpg?fit=752%2C1024&amp;ssl=1\" data-id=\"19207\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Las-palmas-del-Valle-del-Cocora-752x1024-1.jpg?resize=752%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19207\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Las-palmas-del-Valle-del-Cocora-752x1024-1.jpg?w=752&amp;ssl=1 752w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Las-palmas-del-Valle-del-Cocora-752x1024-1.jpg?resize=220%2C300&amp;ssl=1 220w\" sizes=\"auto, (max-width: 752px) 100vw, 752px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1024\" data-attachment-id=\"19208\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/que-es-el-valle-del-cocora-800x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Que-es-el-Valle-del-Cocora-800x1024-1.jpg?fit=800%2C1024&amp;ssl=1\" data-orig-size=\"800,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Que-es-el-Valle-del-Cocora-800&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Que-es-el-Valle-del-Cocora-800x1024-1.jpg?fit=234%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Que-es-el-Valle-del-Cocora-800x1024-1.jpg?fit=800%2C1024&amp;ssl=1\" data-id=\"19208\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Que-es-el-Valle-del-Cocora-800x1024-1.jpg?resize=800%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19208\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Que-es-el-Valle-del-Cocora-800x1024-1.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Que-es-el-Valle-del-Cocora-800x1024-1.jpg?resize=234%2C300&amp;ssl=1 234w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Que-es-el-Valle-del-Cocora-800x1024-1.jpg?resize=768%2C983&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Foresta di palme nella Valle del Cocora @tom_juenemann<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2-Acaime-la-riserva-dei-colibri\"><\/span><strong>2. Acaime: la riserva dei colibr\u00ec<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Un&#8217;altra tappa essenziale \u00e8 Acaime, una riserva di colibr\u00ec. Qui si pu\u00f2 fare una pausa e guardare le piccole creature che sbattono le ali mentre bevono dai trogoli di nettare e si fanno fotografare. L&#8217;ingresso alla riserva \u00e8 di 5000 $COP (1,1\u20ac) e include una bevanda fredda o la tipica bevanda regionale aguapanela con formaggio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3-Punti-panoramici\"><\/span><strong>3. Punti panoramici<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Lungo il percorso si possono trovare diversi punti panoramici dove ci si pu\u00f2 fermare per fare una pausa e scattare foto dei panorami mozzafiato.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-attachment-id=\"19209\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/visitare-valle-del-cocora-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-valle-del-cocora.jpg?fit=1024%2C683&amp;ssl=1\" data-orig-size=\"1024,683\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"visitare-valle-del-cocora\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-valle-del-cocora.jpg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-valle-del-cocora.jpg?fit=1024%2C683&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-valle-del-cocora.jpg?resize=1024%2C683&#038;ssl=1\" alt=\"visitare valle del cocora\" class=\"wp-image-19209\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-valle-del-cocora.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-valle-del-cocora.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-valle-del-cocora.jpg?resize=768%2C512&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Punti panoramici della Valle del Cocora @Passaporto<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4-Mano-di-Acaime\"><\/span><strong>4. Mano di Acaime<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>In uno dei caff\u00e8 della valle, il Caf\u00e9 La Finca, si trova la Mano de Acaime. Si tratta di un&#8217;enorme scultura a forma di mano, situata strategicamente in uno dei luoghi pi\u00f9 fotogenici della Valle della Cocora. Pu\u00f2 essere raggiunta tramite una scala e fotografata in cima. Questa enorme mano per i turisti aggiunge ancora un altro punto di immensit\u00e0 al paesaggio, poich\u00e9 ci si sente minuscoli quando ci si trova sopra.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cosa-fare-nella-Valle-di-Cocora\"><\/span><strong>Cosa fare nella Valle di Cocora<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1-Trekking-nella-Valle-di-Cocora\"><\/span><strong>1. Trekking nella Valle di Cocora<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>L&#8217;attivit\u00e0 fondamentale della Valle del Cocora \u00e8 la sua stessa esplorazione. Consiste in un trekking di circa 4-6 ore e 14 km. L&#8217;itinerario segue un percorso circolare di moderata complessit\u00e0, anche se a volte dovrete addentrarvi nella giungla e attraversare alcuni ruscelli per mezzo di ponti sospesi in legno che forniscono un ulteriore punto di eccitazione. L&#8217;altitudine massima raggiunta \u00e8 di 3000 metri e il dislivello \u00e8 di poco pi\u00f9 di 50 metri. Essendo un percorso circolare, si pu\u00f2 fare la passeggiata in entrambe le direzioni e ognuna ha i suoi vantaggi e svantaggi.<\/p>\n\n\n\n<p>Se decidi di fare il percorso come indicato, troverai prima il bellissimo Bosque de las Palmas e dopo 1 chilometro di cammino in leggera salita arriverai alla Finca La Monta\u00f1a, il punto pi\u00f9 alto del percorso a 3000 metri sul livello del mare. Da qui si pu\u00f2 godere di quella che molti considerano la migliore vista di tutta la Valle del Cocora. Il tour prosegue poi verso la Riserva opzionale dei colibr\u00ec (5000 $COP) che vale la pena di visitare se si desidera vedere questi affascinanti animaletti. Se non hai molto tempo, o semplicemente non hai voglia di andarci, ti consigliamo di seguire il percorso direttamente nella giungla, dove troverai belle cascate e attraverserai i ruscelli su ponti di legno. Questo percorso \u00e8 pi\u00f9 facile perch\u00e9 ci sono meno colline in cima.<\/p>\n\n\n\n<p>L&#8217;altra opzione \u00e8 quella di fare il trekking in senso antiorario, che rende la salita pi\u00f9 difficile, ma ti ricompensa con la Foresta delle Palme nel pomeriggio, che, come al solito, sar\u00e0 probabilmente avvolta dalla nebbia. \u00c8 una buona opzione se sei uno di quelli che preferiscono conservare il meglio per ultimo.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"942\" height=\"1024\" data-attachment-id=\"19210\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/trekking-en-el-valle-del-cocora-942x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Trekking-en-el-Valle-del-Cocora-942x1024-1.jpg?fit=942%2C1024&amp;ssl=1\" data-orig-size=\"942,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Trekking-en-el-Valle-del-Cocora-942&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Trekking-en-el-Valle-del-Cocora-942x1024-1.jpg?fit=276%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Trekking-en-el-Valle-del-Cocora-942x1024-1.jpg?fit=942%2C1024&amp;ssl=1\" data-id=\"19210\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Trekking-en-el-Valle-del-Cocora-942x1024-1.jpg?resize=942%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19210\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Trekking-en-el-Valle-del-Cocora-942x1024-1.jpg?w=942&amp;ssl=1 942w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Trekking-en-el-Valle-del-Cocora-942x1024-1.jpg?resize=276%2C300&amp;ssl=1 276w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Trekking-en-el-Valle-del-Cocora-942x1024-1.jpg?resize=768%2C835&amp;ssl=1 768w\" sizes=\"auto, (max-width: 942px) 100vw, 942px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"959\" height=\"1024\" data-attachment-id=\"19211\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/cocora-coolombia-959x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Cocora-Coolombia-959x1024-1.jpg?fit=959%2C1024&amp;ssl=1\" data-orig-size=\"959,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Cocora-Coolombia-959&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Cocora-Coolombia-959x1024-1.jpg?fit=281%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Cocora-Coolombia-959x1024-1.jpg?fit=959%2C1024&amp;ssl=1\" data-id=\"19211\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Cocora-Coolombia-959x1024-1.jpg?resize=959%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19211\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Cocora-Coolombia-959x1024-1.jpg?w=959&amp;ssl=1 959w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Cocora-Coolombia-959x1024-1.jpg?resize=281%2C300&amp;ssl=1 281w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Cocora-Coolombia-959x1024-1.jpg?resize=768%2C820&amp;ssl=1 768w\" sizes=\"auto, (max-width: 959px) 100vw, 959px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"993\" height=\"1024\" data-attachment-id=\"19212\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/valle-del-cocora-trekking-993x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Trekking-993x1024-1.jpg?fit=993%2C1024&amp;ssl=1\" data-orig-size=\"993,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Valle-del-Cocora-Trekking-993&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Trekking-993x1024-1.jpg?fit=291%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Trekking-993x1024-1.jpg?fit=993%2C1024&amp;ssl=1\" data-id=\"19212\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Trekking-993x1024-1.jpg?resize=993%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19212\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Trekking-993x1024-1.jpg?w=993&amp;ssl=1 993w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Trekking-993x1024-1.jpg?resize=291%2C300&amp;ssl=1 291w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-Cocora-Trekking-993x1024-1.jpg?resize=768%2C792&amp;ssl=1 768w\" sizes=\"auto, (max-width: 993px) 100vw, 993px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Trekking nella Valle del Cocora<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2-Giro-a-cavallo\"><\/span>2. Giro a cavallo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Un altro bel modo di fare il percorso attraverso la Valle della Cocora \u00e8 a cavallo. L&#8217;azienda Bosques de Cocora &#8220;Donde Juan B&#8221; offre molti dei servizi che si possono fare nella valle e questo \u00e8 uno di loro. Il piano \u00e8 di una o due ore e comprende una guida che spiegher\u00e0 tutte le curiosit\u00e0 della valle. Se vuoi fare questo piano ma non hai esperienza a cavallo, non preoccuparti, il percorso \u00e8 semplice su una strada sterrata quindi non avrai alcuna difficolt\u00e0.<\/p>\n\n\n\n<p>I prezzi per questa avventura, anche se dipendono dal numero di persone nel gruppo, si aggirano intorno ai 25 \u20ac per le corse di 1 ora e 40 \u20ac per quelle di 2 ore. Il viaggio include il pranzo e le bevande e i gruppi devono avere almeno due persone.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"821\" height=\"1024\" data-attachment-id=\"19213\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/valle-del-cocora-que-ver-821x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-que-ver-821x1024-1.jpg?fit=821%2C1024&amp;ssl=1\" data-orig-size=\"821,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Valle-del-cocora-que-ver-821&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-que-ver-821x1024-1.jpg?fit=241%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-que-ver-821x1024-1.jpg?fit=821%2C1024&amp;ssl=1\" data-id=\"19213\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-que-ver-821x1024-1.jpg?resize=821%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19213\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-que-ver-821x1024-1.jpg?w=821&amp;ssl=1 821w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-que-ver-821x1024-1.jpg?resize=241%2C300&amp;ssl=1 241w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-que-ver-821x1024-1.jpg?resize=768%2C958&amp;ssl=1 768w\" sizes=\"auto, (max-width: 821px) 100vw, 821px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"757\" height=\"1024\" data-attachment-id=\"19214\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/valle-del-cocora-salento-757x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-Salento-757x1024-1.jpg?fit=757%2C1024&amp;ssl=1\" data-orig-size=\"757,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Valle-del-cocora-Salento-757&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-Salento-757x1024-1.jpg?fit=222%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-Salento-757x1024-1.jpg?fit=757%2C1024&amp;ssl=1\" data-id=\"19214\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-Salento-757x1024-1.jpg?resize=757%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19214\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-Salento-757x1024-1.jpg?w=757&amp;ssl=1 757w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Valle-del-cocora-Salento-757x1024-1.jpg?resize=222%2C300&amp;ssl=1 222w\" sizes=\"auto, (max-width: 757px) 100vw, 757px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Tour nella Valle del Cocora @parisexplorer<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3-Picnic\"><\/span><strong>3. Picnic<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Una volta arrivato nella Valle di Cocora non troverai un posto dove fermarti per mangiare un boccone o per bere dell&#8217;acqua. Per questo motivo, molti visitatori scelgono di fare un picnic seduti tranquillamente di fronte a uno dei panorami pi\u00f9 mozzafiato della Colombia. Infatti, se non vuoi fare shopping, molti stabilimenti e hotel locali offrono un servizio di picnic. Questa attivit\u00e0 \u00e8 cos\u00ec comune che nelle aree di campeggio vengono persino organizzati picnic romantici per coppie con decorazioni in stile San Valentino e pranzi elaborati per 210.000 dollari (46 euro) a coppia.<\/p>\n\n\n\n<p>Se decidi di fare un picnic, e soprattutto se lo fai fuori dall&#8217;area di campeggio e ospitalit\u00e0, non dimenticare di raccogliere i tuoi rifiuti prima di continuare il tuo percorso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4-Yoga\"><\/span><strong>4. Yoga<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>L&#8217;azienda Bosques de Cocora &#8220;Donde Juan B&#8221; offre anche questa sessione di Yoga per gruppi in pieno contatto con la natura. L&#8217;attivit\u00e0 comprende un pranzo delizioso e molto completo a base di trota dorata, insalata di campagna, degustazione di consomm\u00e9 di trota, salse, ecc, pi\u00f9 un altro spuntino nel pomeriggio. Il prezzo \u00e8 di 77.700$ COP (17\u20ac) a persona, tariffa di gruppo per 10 persone.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.passporterapp.android&amp;gl=IT\" style=\"background-color:#2a7057\" target=\"_blank\" rel=\"noreferrer noopener\">scarica l&#8217;app Passporter, \u00e8 gratis! \ud83d\ude09<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5-Piantare-una-palma\"><\/span><strong>5. Piantare una palma<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>La stessa azienda offre un&#8217;altra attivit\u00e0 che non pu\u00f2 mancare nell&#8217;itinerario di chi ama la natura e si impegna per l&#8217;ambiente. Come abbiamo detto prima, la Palma di cera, l&#8217;albero nazionale della Colombia, \u00e8 in pericolo di estinzione; quindi, c&#8217;\u00e8 una bella iniziativa che consiste nel piantare e adottare una palma. L&#8217;attivit\u00e0 include un discorso ecologico sulla palma e il parco naturale della Valle della Cocora. Il prezzo della piantagione \u00e8 di 160.000$ COP (35\u20ac) a persona se fatta individualmente, ma diminuisce a seconda del numero di persone che partecipano all&#8217;attivit\u00e0.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"6-Visita-Salento\"><\/span><strong>6. Visita Salento<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Salento \u00e8 il comune pi\u00f9 antico del dipartimento del Quind\u00edo e il pi\u00f9 vicino alla Valle del Cocora. Dato che il percorso verso la valle si fa in un giorno, ti consigliamo di cogliere l&#8217;occasione per visitare questa pittoresca cittadina che ti conquister\u00e0 con i suoi colori e la cordialit\u00e0 della sua gente. Questo \u00e8 quello che non si pu\u00f2 perdere:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Plaza de Sim\u00f3n Bol\u00edvar<\/strong>: oltre ad essere il luogo dove si prende la Willys Jeep per la Valle del Cocora, questa piazza \u00e8 un alveare di vita e vita notturna il sabato, che contrasta con la pace della messa domenicale nella chiesa di Nuestra Se\u00f1ora del Carmen de Salento.<\/li>\n\n\n\n<li><strong>Calle Real<\/strong>: Mentre tutte le strade della citt\u00e0 meritano di essere percorse con la loro architettura bianca e dai colori vivaci, se dobbiamo sceglierne solo una, Calle Real non dovrebbe mancare nel tuo itinerario.<\/li>\n\n\n\n<li><strong>Portarsi a casa l&#8217;autentico caff\u00e8 colombiano<\/strong>: approfittate di essere nell&#8217;Eje Cafetero per portare a casa uno (o forse qualche altro) pacchetto di caff\u00e8 colombiano comprato alla <strong>Tienda Caf\u00e9 Salento<\/strong> in Calle Real.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"784\" height=\"1024\" data-attachment-id=\"19215\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/eje-cafetero-colombia-784x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/eje-cafetero-colombia-784x1024-1.jpg?fit=784%2C1024&amp;ssl=1\" data-orig-size=\"784,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"eje-cafetero-colombia-784&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/eje-cafetero-colombia-784x1024-1.jpg?fit=230%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/eje-cafetero-colombia-784x1024-1.jpg?fit=784%2C1024&amp;ssl=1\" data-id=\"19215\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/eje-cafetero-colombia-784x1024-1.jpg?resize=784%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19215\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/eje-cafetero-colombia-784x1024-1.jpg?w=784&amp;ssl=1 784w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/eje-cafetero-colombia-784x1024-1.jpg?resize=230%2C300&amp;ssl=1 230w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/eje-cafetero-colombia-784x1024-1.jpg?resize=768%2C1003&amp;ssl=1 768w\" sizes=\"auto, (max-width: 784px) 100vw, 784px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"1024\" data-attachment-id=\"19216\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/visita-eje-cafetero-colombia-740x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visita-eje-cafetero-colombia-740x1024-1.jpg?fit=740%2C1024&amp;ssl=1\" data-orig-size=\"740,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"visita-eje-cafetero-colombia-740&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visita-eje-cafetero-colombia-740x1024-1.jpg?fit=217%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visita-eje-cafetero-colombia-740x1024-1.jpg?fit=740%2C1024&amp;ssl=1\" data-id=\"19216\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visita-eje-cafetero-colombia-740x1024-1.jpg?resize=740%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19216\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visita-eje-cafetero-colombia-740x1024-1.jpg?w=740&amp;ssl=1 740w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visita-eje-cafetero-colombia-740x1024-1.jpg?resize=217%2C300&amp;ssl=1 217w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"754\" height=\"1024\" data-attachment-id=\"19217\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/salento-eje-cafetero-de-colombia-754x1024-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Salento-eje-cafetero-de-colombia-754x1024-1.jpg?fit=754%2C1024&amp;ssl=1\" data-orig-size=\"754,1024\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Salento-eje-cafetero-de-colombia-754&amp;#215;1024-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Salento-eje-cafetero-de-colombia-754x1024-1.jpg?fit=221%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Salento-eje-cafetero-de-colombia-754x1024-1.jpg?fit=754%2C1024&amp;ssl=1\" data-id=\"19217\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Salento-eje-cafetero-de-colombia-754x1024-1.jpg?resize=754%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-19217\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Salento-eje-cafetero-de-colombia-754x1024-1.jpg?w=754&amp;ssl=1 754w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Salento-eje-cafetero-de-colombia-754x1024-1.jpg?resize=221%2C300&amp;ssl=1 221w\" sizes=\"auto, (max-width: 754px) 100vw, 754px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Tour della fattoria del caff\u00e8 del Salento &#8211; Eje Cafetero Colombia @jovi_travel<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-attachment-id=\"19218\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/calle-real-a-salento-colombia\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-a-Salento-Colombia.jpeg?fit=1024%2C768&amp;ssl=1\" data-orig-size=\"1024,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Calle-real-a-Salento-Colombia\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-a-Salento-Colombia.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-a-Salento-Colombia.jpeg?fit=1024%2C768&amp;ssl=1\" data-id=\"19218\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-a-Salento-Colombia.jpeg?resize=1024%2C768&#038;ssl=1\" alt=\"\" class=\"wp-image-19218\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-a-Salento-Colombia.jpeg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-a-Salento-Colombia.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-a-Salento-Colombia.jpeg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-attachment-id=\"19219\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/calle-real-en-salento-1024x575-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-en-Salento-1024x575-1.jpeg?fit=1024%2C575&amp;ssl=1\" data-orig-size=\"1024,575\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Calle-real-en-Salento-1024&amp;#215;575-1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-en-Salento-1024x575-1.jpeg?fit=300%2C168&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-en-Salento-1024x575-1.jpeg?fit=1024%2C575&amp;ssl=1\" data-id=\"19219\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-en-Salento-1024x575-1.jpeg?resize=1024%2C575&#038;ssl=1\" alt=\"\" class=\"wp-image-19219\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-en-Salento-1024x575-1.jpeg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-en-Salento-1024x575-1.jpeg?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/Calle-real-en-Salento-1024x575-1.jpeg?resize=768%2C431&amp;ssl=1 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Calle Real a Salento in Colombia<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Mappa-di-viaggio-Valle-di-Cocora\"><\/span>Mappa di viaggio Valle di Cocora<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Qui vi lasciamo la nostra mappa con i luoghi che vi consigliamo di visitare nella Valle del Cocora, in modo che possiate organizzare il vostro viaggio in modo semplice e veloce. Potete anche aggiungere documenti importanti come biglietti di viaggio, prenotazioni alberghiere e persino invitare i vostri amici a partecipare all&#8217;organizzazione dell&#8217;itinerario.<strong> L&#8217;utilizzo di Passporter \u00e8 gratuito e vi aiuter\u00e0 a viaggiare in modo pi\u00f9 organizzato. <\/strong>Avete la possibilit\u00e0 di organizzare il vostro viaggio sul web registrandovi o di scaricare l&#8217;applicazione per portare tutto in tasca \ud83d\ude42<\/p>\n\n\n\n<p><iframe loading=\"lazy\" width=\"100%\" height=\"400\" style=\"border: 0\" src=\"https:\/\/passporterapp.com\/frame\/itineraries\/3fcd142d-7e88-4632-a7e5-193a0a987f9f?ref=blogpassporter8&amp;utm_source=blog&amp;utm_medium=valle-del-cocora-colombia&amp;utm_term=mapita\"><\/p>\n<p><\/iframe><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Come-raggiungere-la-Valle-del-Cocora\"><\/span><strong>Come raggiungere la Valle del Cocora?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Per arrivare alla Valle del Cocora bisogna innanzitutto raggiungere la citt\u00e0 di Salento, situata a 10 km dalla Valle del Cocora. Se avete un&#8217;auto, potete fare il viaggio da soli e lasciarla nel parcheggio di uno dei ristoranti all&#8217;ingresso della valle. Ma se non avete un&#8217;auto o se preferite farvi accompagnare, potete prendere una delle Jeep <strong>&#8220;Willys&#8221;<\/strong> (il mezzo di trasporto tipico della regione) che partono da Plaza Sim\u00f3n Bol\u00edvar a Salento. Il viaggio costa circa 4000 $COP (&lt;1\u20ac) a persona.<br>Il modo pi\u00f9 semplice per raggiungere Salento \u00e8 volare verso una delle principali citt\u00e0 della regione produttrice di caff\u00e8, come Pereira o Armenia. Una volta arrivati a Pereira o in Armenia, bisogna prendere uno degli autobus per Salento. Da Armenia, ad esempio, Salento dista solo 30 km e il costo di questo viaggio \u00e8 di 4700 $ COP (1&#8217;05 \u20ac). <\/p>\n\n\n\n<p>Se avete tempo, vi consigliamo anche di visitare il villaggio di Finlandia, che \u00e8 molto vicino a Salento e potete anche prendere una delle jeep che vanno a Finlandia.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1000\" data-attachment-id=\"19220\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/come-arrivare-alla-valle-del-cocora\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/come-arrivare-alla-valle-del-cocora.jpg?fit=750%2C1000&amp;ssl=1\" data-orig-size=\"750,1000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"come-arrivare-alla-valle-del-cocora\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/come-arrivare-alla-valle-del-cocora.jpg?fit=225%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/come-arrivare-alla-valle-del-cocora.jpg?fit=750%2C1000&amp;ssl=1\" data-id=\"19220\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/come-arrivare-alla-valle-del-cocora.jpg?resize=750%2C1000&#038;ssl=1\" alt=\"come arrivare alla valle del cocora\" class=\"wp-image-19220\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/come-arrivare-alla-valle-del-cocora.jpg?w=750&amp;ssl=1 750w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/come-arrivare-alla-valle-del-cocora.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"1000\" data-attachment-id=\"19221\" data-permalink=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/attachment\/visitare-finlandia-cocora\/\" data-orig-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-finlandia-cocora.jpeg?fit=600%2C1000&amp;ssl=1\" data-orig-size=\"600,1000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"visitare-finlandia-cocora\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-finlandia-cocora.jpeg?fit=180%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-finlandia-cocora.jpeg?fit=600%2C1000&amp;ssl=1\" data-id=\"19221\" src=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-finlandia-cocora.jpeg?resize=600%2C1000&#038;ssl=1\" alt=\"visitare finlandia cocora\" class=\"wp-image-19221\" srcset=\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-finlandia-cocora.jpeg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2023\/12\/visitare-finlandia-cocora.jpeg?resize=180%2C300&amp;ssl=1 180w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Scopri come raggiungere la Valle del Cocora in Colombia @ditiraya<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Dove-alloggiare-nella-Valle-di-Cocora\"><\/span>Dove alloggiare nella Valle di Cocora?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Essendo un&#8217;area protetta, non ci sono alloggi all&#8217;interno della Valle della Cocora. Tuttavia, al suo ingresso c&#8217;\u00e8 una zona con una moltitudine di ristoranti e servizi alberghieri. Ecco alcuni esempi di posti per dormire nella Valle di Cocora.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Camping Valle del Cocora<\/strong>: un campeggio tradizionale con tenda inclusa, servizi igienici e docce, parcheggio, caricabatterie per cellulari e zona Wifi. (8,8\u20ac a notte)<\/li>\n\n\n\n<li><strong>Birdglamping Aviturismo Los \u00c1rboles<\/strong>: questo fantastico glamping ideale per le coppie, oltre ad essere uno dei pi\u00f9 tranquilli e meglio valutati su internet, ha un bagno privato, colazione a buffet inclusa e tutte le comodit\u00e0 di un hotel. (100\u20ac a notte)<\/li>\n\n\n\n<li><strong>Hotel San Jos\u00e9<\/strong>: questa fattoria trasformata in hotel \u00e8 una delle migliori opzioni per un pernottamento vicino alla Valle di Cocora se non vuoi dormire in una tenda. Il prezzo \u00e8 di 17,75\u20ac a notte per persona e comprende una camera con bagno privato e la colazione.<\/li>\n\n\n\n<li><strong>Caba\u00f1as Valle del Cocora La Truchera<\/strong>: bellissime cabine con camera da letto, soggiorno e bagno privato, oltre a fantastiche viste sulla valle e colazione inclusa. Animali domestici ammessi (36-62\u20ac a notte).<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-consigli-per-il-vostro-viaggio-nella-valle-del-cocora\"><span class=\"ez-toc-section\" id=\"Consigli-per-il-vostro-viaggio-nella-Valle-del-Cocora\"><\/span><strong>Consigli per il vostro viaggio nella Valle del Cocora<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Indossate abiti comodi e traspiranti, poich\u00e9 il clima \u00e8 molto umido, nonch\u00e9 un impermeabile e scarpe da trekking.<\/li>\n\n\n\n<li>Portate sempre con voi acqua e cibo. Trattandosi di un parco naturale, non ci sono chioschi dove potersi fermare per ricaricare le batterie.<\/li>\n\n\n\n<li>Viaggiate assicurati per qualsiasi imprevisto. Noi utilizziamo sempre l&#8217;<strong><a href=\"https:\/\/heymondo.it\/?utm_medium=Afiliado&amp;utm_source=PASSPORTER&amp;utm_campaign=PRINCIPAL&amp;cod_descuento=PASSPORTER&amp;ag_campaign=valle-cocora-colombia-lateral&amp;agencia=TmQ6oVUdKUtb48XOjACNv0Y0djarI5oI6wsdlQr5\" target=\"_blank\" rel=\"noreferrer noopener\">assicurazione di viaggio Mondo<\/a><\/strong>.<\/li>\n\n\n\n<li>Indossate un repellente per insetti prima di entrare nella giungla.<\/li>\n\n\n\n<li>Organizzate il vostro itinerario di viaggio con i luoghi che visiterete nell&#8217;<strong><a href=\"https:\/\/passporterapp.com\/it\/auth\/signup?ref=blogpassporter&amp;utm_source=blog&amp;utm_medium=que-ver-en-rabat&amp;utm_term=registro-gratis\" target=\"_blank\" rel=\"noreferrer noopener\">App gratuita Passporter<\/a><\/strong>.<\/li>\n\n\n\n<li>Prendetevi cura del parco. Riponete i rifiuti se non trovate i cestini, non gettateli mai per terra.<\/li>\n\n\n\n<li>Non accendete fuochi in aree non predisposte.<\/li>\n\n\n\n<li>Acquistate una <strong><a href=\"https:\/\/esim.holafly.com\/it\/esim-colombia\/?ref=passportertechnologies&amp;discount=PASSPORTER&amp;utm_source=passportertechnologies_blog&amp;utm_medium=affiliation&amp;utm_campaign=esim-colombia\" target=\"_blank\" rel=\"noreferrer noopener\">eSIM per rimanere connessi a Internet<\/a> <\/strong>e restate sempre in contatto con i vostri cari.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-come-organizzare-il-vostro-viaggio-nella-valle-del-cocora\"><span class=\"ez-toc-section\" id=\"Come-organizzare-il-vostro-viaggio-nella-Valle-del-Cocora\"><\/span><strong>Come organizzare il vostro viaggio nella Valle del Cocora?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Registratevi o scaricate l&#8217;app Passporter e approfittate di tutti i suoi vantaggi:<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background wp-element-button\" href=\"https:\/\/passporterapp.com\/it\/auth\/signup?ref=blogpassporter&amp;utm_source=blog&amp;utm_medium=que-ver-en-rabat&amp;utm_term=registro-gratis\" style=\"background-color:#2a7057\" target=\"_blank\" rel=\"noreferrer noopener\">registrati gratuitamente su passporter<\/a><\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lasciatevi ispirare dalle esperienze degli altri viaggiatori, dalle loro foto e dai loro itinerari.<\/li>\n\n\n\n<li>Organizzate il vostro viaggio in base alle categorie che preferite: date, numero di giorni o tipo di viaggio (spiaggia, montagna, ristoranti\u2026).<\/li>\n\n\n\n<li><strong>Aggiungete i vostri amici<\/strong> in modo che possano vedere e modificare tutti i vostri piani e le informazioni di viaggio.<\/li>\n\n\n\n<li>Create il vostro itinerario della destinazione con tutto ci\u00f2 che volete visitare ogni giorno.<\/li>\n\n\n\n<li>Aggiungete le tappe che vi interessano di pi\u00f9, compresi gli alloggi, i ristoranti, i musei\u2026<\/li>\n\n\n\n<li>Prenotate voli, alloggi, trasferimenti e attivit\u00e0<strong> attraverso un&#8217;unica app.<\/strong><\/li>\n\n\n\n<li><strong>Salvate tutti i documenti nell&#8217;app<\/strong> per avere sempre tutto a portata di mano: prenotazioni, carte d&#8217;imbarco, documenti importanti\u2026<\/li>\n\n\n\n<li>Apportate le modifiche necessarie e tutto sar\u00e0 pronto per il vostro viaggio.<\/li>\n\n\n\n<li><strong>Condividete la vostra esperienza con altri utenti<\/strong>. Caricate sull&#8217;app le foto dei luoghi che avete visitato durante il vostro viaggio e ispirate altri viaggiatori con la vostra esperienza. <\/li>\n<\/ul>\n\n\n\n<p>Se avete dubbi su come fare, potete consultare il nostro post:&nbsp;<strong><a href=\"https:\/\/passporterapp.com\/it\/blog\/viaggio\/itinerario-di-viaggio\/\" target=\"_blank\" rel=\"noreferrer noopener\">Come creare un itinerario di viaggio su Passporter<\/a><\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Domande-frequenti-su-un-viaggio-nella-Valle-di-Cocora\"><\/span><strong>Domande frequenti su un viaggio nella Valle di Cocora<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1637188908441\"><strong class=\"schema-faq-question\">Quanto costa andare nella Valle di Cocora?<\/strong> <p class=\"schema-faq-answer\">Il prezzo di questa avventura dipende dal tuo budget. Questo tour non richiede l&#8217;assunzione di una guida turistica, quindi se si decide di pagare solo l&#8217;ingresso e fare il tour da soli, il prezzo \u00e8 di 9000$ COP (2\u20ac). L&#8217;ingresso alla Riserva dei Colibr\u00ec \u00e8 di 5000$ COP (1&#8217;1\u20ac).<br\/><br\/>Tuttavia, anche se non \u00e8 obbligatorio, l&#8217;opzione di assumere un piano turistico con una guida, il pranzo e anche l&#8217;equitazione e la piantagione di una palma di cera va da COP$64.000 (\u20ac14) a COP$282.000 (&lt;\u20ac65). Il prezzo dipende dal numero di servizi inclusi nel pacchetto e dal numero di ore che si desidera trascorrere nella Valle di Cocora.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1637188931441\"><strong class=\"schema-faq-question\">Come arrivare<\/strong> <p class=\"schema-faq-answer\">Per andare alla Valle di Cocora bisogna prima arrivare al villaggio di Salento, situato a 10 km dalla valle. Se hai una macchina, puoi fare il viaggio da solo e lasciarla nel parcheggio di uno dei ristoranti all&#8217;entrata della valle. Ma se non hai una macchina o se preferisci lasciarti accompagnare, puoi prendere una delle Jeep &#8220;Willys&#8221; (il trasporto tipico della regione) che partono dalla Plaza Sim\u00f3n Bol\u00edvar nel Salento. Il viaggio costa circa 4000 $COP (&lt;1\u20ac) a persona.<br\/>Il modo pi\u00f9 semplice per raggiungere il Salento \u00e8 prendere uno degli autobus che partono dalle principali citt\u00e0 dell&#8217;Eje Cafetero, come Armenia, che dista solo 30 km. Il costo di questo viaggio \u00e8 di 4700$ COP (1,05 \u20ac).<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1637189099220\"><strong class=\"schema-faq-question\">Com&#8217;\u00e8 il tempo nella Valle di Cocora?<\/strong> <p class=\"schema-faq-answer\">Il clima \u00e8 umido, con nebbia e piogge quasi tutti i giorni dell&#8217;anno. La temperatura media \u00e8 di 15\u00baC con massime di 25\u00baC e minime di 12\u00baC.<\/p> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Valle di Cocora \u00e8 un meraviglioso paesaggio naturale situato nel cuore dell&#8217;Eje Cafetero della Colombia. L\u00ec si possono osservare le palme pi\u00f9 alte del mondo che si perdono nella nebbia al tramonto, creando una vista tanto bella quanto magica e spettrale. Ti invitiamo a scoprire le attivit\u00e0 e le bellezze di questa valle che conquistano ogni avventuriero che ci mette piede. Cos&#8217;\u00e8 la Valle di Cocora? La Valle di Cocora \u00e8 un meraviglioso paesaggio naturale situato nella catena montuosa centrale delle Ande colombiane, tra gli alti corsi del fiume Quindio. Pi\u00f9 precisamente, nella citt\u00e0 di Salento, a 30 km da Armenia, nel dipartimento di Quind\u00edo, uno dei punti chiave dell&#8217;Eje Cafetero. Questa valle \u00e8 anche una delle entrate del Parque Nacional Natural de los Nevados, un enorme parco protetto di 583 km\u00b2 caratterizzato da [&hellip;]<\/p>\n","protected":false},"author":183705615,"featured_media":14042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1471],"tags":[],"class_list":["post-14041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colombia"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.0 (Yoast SEO v24.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Valle di Cocora in Colombia - Passporter Blog<\/title>\n<meta name=\"description\" content=\"Scopri la Valle di Cocora, uno dei panorami pi\u00f9 mozzafiato della Colombia dove il tuo sguardo si perde tra le palme pi\u00f9 alte del mondo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valle di Cocora in Colombia\" \/>\n<meta property=\"og:description\" content=\"Scopri la Valle di Cocora, uno dei panorami pi\u00f9 mozzafiato della Colombia dove il tuo sguardo si perde tra le palme pi\u00f9 alte del mondo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/\" \/>\n<meta property=\"og:site_name\" content=\"Passporter Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-29T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-29T12:07:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2021\/11\/valle-dei-cocora-colombia.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"andreacayonsanchiz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"andreacayonsanchiz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/\",\"url\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/\",\"name\":\"Valle di Cocora in Colombia - Passporter Blog\",\"isPartOf\":{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2021\/11\/valle-dei-cocora-colombia.jpeg?fit=800%2C533&ssl=1\",\"datePublished\":\"2023-12-29T10:00:00+00:00\",\"dateModified\":\"2023-12-29T12:07:38+00:00\",\"author\":{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/#\/schema\/person\/0098c0d4bae833b9c214374910073b90\"},\"description\":\"Scopri la Valle di Cocora, uno dei panorami pi\u00f9 mozzafiato della Colombia dove il tuo sguardo si perde tra le palme pi\u00f9 alte del mondo.\",\"breadcrumb\":{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637188908441\"},{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637188931441\"},{\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637189099220\"}],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2021\/11\/valle-dei-cocora-colombia.jpeg?fit=800%2C533&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2021\/11\/valle-dei-cocora-colombia.jpeg?fit=800%2C533&ssl=1\",\"width\":800,\"height\":533,\"caption\":\"Valle di Cocora in Colombia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/passporterapp.com\/it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valle di Cocora in Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/#website\",\"url\":\"https:\/\/passporterapp.com\/it\/blog\/\",\"name\":\"Passporter Blog\",\"description\":\"Passporter Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/passporterapp.com\/it\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/#\/schema\/person\/0098c0d4bae833b9c214374910073b90\",\"name\":\"andreacayonsanchiz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/56e09070bf83d8cfdc5a8920ecc405e79ebf8c3afec319cce933e05fa0b12aac?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/56e09070bf83d8cfdc5a8920ecc405e79ebf8c3afec319cce933e05fa0b12aac?s=96&d=identicon&r=g\",\"caption\":\"andreacayonsanchiz\"},\"url\":\"https:\/\/passporterapp.com\/it\/blog\/author\/andreacayonsanchiz\/\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637188908441\",\"position\":1,\"url\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637188908441\",\"name\":\"Quanto costa andare nella Valle di Cocora?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Il prezzo di questa avventura dipende dal tuo budget. Questo tour non richiede l'assunzione di una guida turistica, quindi se si decide di pagare solo l'ingresso e fare il tour da soli, il prezzo \u00e8 di 9000$ COP (2\u20ac). L'ingresso alla Riserva dei Colibr\u00ec \u00e8 di 5000$ COP (1'1\u20ac).<br\/><br\/>Tuttavia, anche se non \u00e8 obbligatorio, l'opzione di assumere un piano turistico con una guida, il pranzo e anche l'equitazione e la piantagione di una palma di cera va da COP$64.000 (\u20ac14) a COP$282.000 (&lt;\u20ac65). Il prezzo dipende dal numero di servizi inclusi nel pacchetto e dal numero di ore che si desidera trascorrere nella Valle di Cocora.\",\"inLanguage\":\"it-IT\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637188931441\",\"position\":2,\"url\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637188931441\",\"name\":\"Come arrivare\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Per andare alla Valle di Cocora bisogna prima arrivare al villaggio di Salento, situato a 10 km dalla valle. Se hai una macchina, puoi fare il viaggio da solo e lasciarla nel parcheggio di uno dei ristoranti all'entrata della valle. Ma se non hai una macchina o se preferisci lasciarti accompagnare, puoi prendere una delle Jeep \\\"Willys\\\" (il trasporto tipico della regione) che partono dalla Plaza Sim\u00f3n Bol\u00edvar nel Salento. Il viaggio costa circa 4000 $COP (&lt;1\u20ac) a persona.<br\/>Il modo pi\u00f9 semplice per raggiungere il Salento \u00e8 prendere uno degli autobus che partono dalle principali citt\u00e0 dell'Eje Cafetero, come Armenia, che dista solo 30 km. Il costo di questo viaggio \u00e8 di 4700$ COP (1,05 \u20ac).\",\"inLanguage\":\"it-IT\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"Question\",\"@id\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637189099220\",\"position\":3,\"url\":\"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637189099220\",\"name\":\"Com'\u00e8 il tempo nella Valle di Cocora?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Il clima \u00e8 umido, con nebbia e piogge quasi tutti i giorni dell'anno. La temperatura media \u00e8 di 15\u00baC con massime di 25\u00baC e minime di 12\u00baC.\",\"inLanguage\":\"it-IT\"},\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Valle di Cocora in Colombia - Passporter Blog","description":"Scopri la Valle di Cocora, uno dei panorami pi\u00f9 mozzafiato della Colombia dove il tuo sguardo si perde tra le palme pi\u00f9 alte del mondo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/","og_locale":"it_IT","og_type":"article","og_title":"Valle di Cocora in Colombia","og_description":"Scopri la Valle di Cocora, uno dei panorami pi\u00f9 mozzafiato della Colombia dove il tuo sguardo si perde tra le palme pi\u00f9 alte del mondo.","og_url":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/","og_site_name":"Passporter Blog","article_published_time":"2023-12-29T10:00:00+00:00","article_modified_time":"2023-12-29T12:07:38+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2021\/11\/valle-dei-cocora-colombia.jpeg","type":"image\/jpeg"}],"author":"andreacayonsanchiz","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"andreacayonsanchiz","Tempo di lettura stimato":"17 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","FAQPage"],"@id":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/","url":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/","name":"Valle di Cocora in Colombia - Passporter Blog","isPartOf":{"@id":"https:\/\/passporterapp.com\/it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#primaryimage"},"image":{"@id":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2021\/11\/valle-dei-cocora-colombia.jpeg?fit=800%2C533&ssl=1","datePublished":"2023-12-29T10:00:00+00:00","dateModified":"2023-12-29T12:07:38+00:00","author":{"@id":"https:\/\/passporterapp.com\/it\/blog\/#\/schema\/person\/0098c0d4bae833b9c214374910073b90"},"description":"Scopri la Valle di Cocora, uno dei panorami pi\u00f9 mozzafiato della Colombia dove il tuo sguardo si perde tra le palme pi\u00f9 alte del mondo.","breadcrumb":{"@id":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637188908441"},{"@id":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637188931441"},{"@id":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637189099220"}],"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#primaryimage","url":"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2021\/11\/valle-dei-cocora-colombia.jpeg?fit=800%2C533&ssl=1","contentUrl":"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2021\/11\/valle-dei-cocora-colombia.jpeg?fit=800%2C533&ssl=1","width":800,"height":533,"caption":"Valle di Cocora in Colombia"},{"@type":"BreadcrumbList","@id":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/passporterapp.com\/it\/blog\/"},{"@type":"ListItem","position":2,"name":"Valle di Cocora in Colombia"}]},{"@type":"WebSite","@id":"https:\/\/passporterapp.com\/it\/blog\/#website","url":"https:\/\/passporterapp.com\/it\/blog\/","name":"Passporter Blog","description":"Passporter Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/passporterapp.com\/it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/passporterapp.com\/it\/blog\/#\/schema\/person\/0098c0d4bae833b9c214374910073b90","name":"andreacayonsanchiz","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/passporterapp.com\/it\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/56e09070bf83d8cfdc5a8920ecc405e79ebf8c3afec319cce933e05fa0b12aac?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56e09070bf83d8cfdc5a8920ecc405e79ebf8c3afec319cce933e05fa0b12aac?s=96&d=identicon&r=g","caption":"andreacayonsanchiz"},"url":"https:\/\/passporterapp.com\/it\/blog\/author\/andreacayonsanchiz\/"},{"@type":"Question","@id":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637188908441","position":1,"url":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637188908441","name":"Quanto costa andare nella Valle di Cocora?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Il prezzo di questa avventura dipende dal tuo budget. Questo tour non richiede l'assunzione di una guida turistica, quindi se si decide di pagare solo l'ingresso e fare il tour da soli, il prezzo \u00e8 di 9000$ COP (2\u20ac). L'ingresso alla Riserva dei Colibr\u00ec \u00e8 di 5000$ COP (1'1\u20ac).<br\/><br\/>Tuttavia, anche se non \u00e8 obbligatorio, l'opzione di assumere un piano turistico con una guida, il pranzo e anche l'equitazione e la piantagione di una palma di cera va da COP$64.000 (\u20ac14) a COP$282.000 (&lt;\u20ac65). Il prezzo dipende dal numero di servizi inclusi nel pacchetto e dal numero di ore che si desidera trascorrere nella Valle di Cocora.","inLanguage":"it-IT"},"inLanguage":"it-IT"},{"@type":"Question","@id":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637188931441","position":2,"url":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637188931441","name":"Come arrivare","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Per andare alla Valle di Cocora bisogna prima arrivare al villaggio di Salento, situato a 10 km dalla valle. Se hai una macchina, puoi fare il viaggio da solo e lasciarla nel parcheggio di uno dei ristoranti all'entrata della valle. Ma se non hai una macchina o se preferisci lasciarti accompagnare, puoi prendere una delle Jeep \"Willys\" (il trasporto tipico della regione) che partono dalla Plaza Sim\u00f3n Bol\u00edvar nel Salento. Il viaggio costa circa 4000 $COP (&lt;1\u20ac) a persona.<br\/>Il modo pi\u00f9 semplice per raggiungere il Salento \u00e8 prendere uno degli autobus che partono dalle principali citt\u00e0 dell'Eje Cafetero, come Armenia, che dista solo 30 km. Il costo di questo viaggio \u00e8 di 4700$ COP (1,05 \u20ac).","inLanguage":"it-IT"},"inLanguage":"it-IT"},{"@type":"Question","@id":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637189099220","position":3,"url":"https:\/\/passporterapp.com\/it\/blog\/colombia\/valle-cocora-colombia\/#faq-question-1637189099220","name":"Com'\u00e8 il tempo nella Valle di Cocora?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Il clima \u00e8 umido, con nebbia e piogge quasi tutti i giorni dell'anno. La temperatura media \u00e8 di 15\u00baC con massime di 25\u00baC e minime di 12\u00baC.","inLanguage":"it-IT"},"inLanguage":"it-IT"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/passporterapp.com\/it\/blog\/wp-content\/uploads\/2021\/11\/valle-dei-cocora-colombia.jpeg?fit=800%2C533&ssl=1","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pd1Cww-3Et","_links":{"self":[{"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/posts\/14041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/users\/183705615"}],"replies":[{"embeddable":true,"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/comments?post=14041"}],"version-history":[{"count":0,"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/posts\/14041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/media\/14042"}],"wp:attachment":[{"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/media?parent=14041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/categories?post=14041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/passporterapp.com\/it\/blog\/wp-json\/wp\/v2\/tags?post=14041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}